{"id":62464,"date":"2022-02-01T12:15:41","date_gmt":"2022-02-01T05:15:41","guid":{"rendered":"https:\/\/sokxaygroup.com\/sxgroup\/?page_id=62464"},"modified":"2022-02-01T12:29:13","modified_gmt":"2022-02-01T05:29:13","slug":"%e0%ba%9a%e0%ba%b1%e0%ba%99%e0%ba%94%e0%ba%b2-%e0%ba%ab%e0%ba%bb%e0%ba%a7%e0%bb%9c%e0%bb%89%e0%ba%b2-%e0%ba%ab%e0%ba%bb%e0%ba%a7%e0%bb%9c%e0%bb%88%e0%ba%a7%e0%ba%8d%e0%ba%97%e0%ba%b8%e0%ba%a5%e0%ba%b0","status":"publish","type":"page","link":"https:\/\/sokxaygroup.com\/sxgroup\/%e0%ba%9a%e0%ba%b1%e0%ba%99%e0%ba%94%e0%ba%b2-%e0%ba%ab%e0%ba%bb%e0%ba%a7%e0%bb%9c%e0%bb%89%e0%ba%b2-%e0%ba%ab%e0%ba%bb%e0%ba%a7%e0%bb%9c%e0%bb%88%e0%ba%a7%e0%ba%8d%e0%ba%97%e0%ba%b8%e0%ba%a5%e0%ba%b0\/","title":{"rendered":"\u0e9a\u0eb1\u0e99\u0e94\u0eb2 \u0eab\u0ebb\u0ea7\u0edc\u0ec9\u0eb2 \u0eab\u0ebb\u0ea7\u0edc\u0ec8\u0ea7\u0e8d\u0e97\u0eb8\u0ea5\u0eb0\u0e81\u0eb4\u0e94 \u0e82\u0ead\u0e87\u0e81\u0eb8\u0ec8\u0ea1\u0e9a\u0ecd\u0ea5\u0eb4\u0eaa\u0eb1\u0e94\u0ec2\u0e8a\u0e81\u0ec4\u0e8a"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row type=&#8221;vc_default&#8221; bg_type=&#8221;image&#8221; parallax_style=&#8221;vcpb-default&#8221; bg_image_new=&#8221;id^60302|url^https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2019\/11\/bg-dev-studio-05.jpg|caption^null|alt^null|title^bg-dev-studio-05|description^null&#8221; bg_image_repeat=&#8221;no-repeat&#8221; bg_override=&#8221;full&#8221; css=&#8221;.vc_custom_1643693252938{margin-top: 50px !important;}&#8221;][vc_column]<div id=\"ultimate-heading-34406a049c6533f9f\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-34406a049c6533f9f uvc-4028 accent-border-color\" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-34406a049c6533f9f h2'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}' ><h2 style=\"font-weight:bold;color:#ffffff;margin-top:20px;\">\u0e9a\u0eb1\u0e99\u0e94\u0eb2 \u0eab\u0ebb\u0ea7\u0edc\u0ec9\u0eb2 \u0eab\u0ebb\u0ea7\u0edc\u0ec8\u0ea7\u0e8d\u0e97\u0eb8\u0ea5\u0eb0\u0e81\u0eb4\u0e94 \u0e82\u0ead\u0e87\u0e81\u0eb8\u0ec8\u0ea1\u0e9a\u0ecd\u0ea5\u0eb4\u0eaa\u0eb1\u0e94\u0ec2\u0e8a\u0e81\u0ec4\u0e8a<\/h2><\/div><\/div>[vc_row_inner][vc_column_inner css=&#8221;.vc_custom_1643693051470{margin-top: 50px !important;}&#8221;]<style type=\"text\/css\" data-type=\"the7_shortcodes-inline-css\">.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940.content-bg-on .team-container {\n  background: rgba(0,0,0,0.73);\n  -webkit-box-shadow: none;\n  box-shadow: none;\n}\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940 .team-desc {\n  padding: 10px 10px 10px 10px;\n}\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940 .team-author-name,\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940 .team-author-name a {\n  color: #ffffff;\n  background: none;\n  margin-bottom: 0px;\n  font-size: 18px;\n  line-height: 26px;\n  font-weight: bold;\n}\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940 .post-details.details-type-link,\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940 .post-details.details-type-link * {\n  color: #ffffff;\n  background: none;\n}\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940 .team-author p {\n  margin-bottom: 10px;\n  font-size: 14px;\n  line-height: 18px;\n  font-weight: bold;\n}\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940  .team-media {\n  padding: 10px 10px 10px 10px;\n}\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940  .team-media a,\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940  .team-media > span,\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940  .team-media img {\n  max-width: 230px;\n}\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940 .dt-css-grid .team-media img {\n  width: 230px;\n  max-width: 100%;\n}\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940 .team-content {\n  margin-bottom: 5px;\n}\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940  .team-media,\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940  .team-media a.rollover,\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940  .team-media a.rollover *,\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940  .team-media img {\n  border-radius: 360px;\n}\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940 .soc-ico {\n  margin-bottom: 15px;\n}\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940 .soc-ico a {\n  min-width: 26px;\n  min-height: 26px;\n  font-size: 16px;\n  border-radius: 100px;\n}\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940 .soc-ico a:not(:last-child) {\n  margin-right: 4px;\n}\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940 .soc-ico a:before,\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940 .soc-ico a:after {\n  min-width: 26px;\n  min-height: 26px;\n  padding: inherit;\n}\n.dt-icon-border-on.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940 .soc-ico a:before {\n  border: 0px solid transparent;\n}\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940 .soc-ico a:hover {\n  font-size: 16px;\n}\n#page .dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940 .soc-ico a:hover .soc-font-icon {\n  color: rgba(255,255,255,0.75);\n  background: none;\n}\n.dt-icon-border-hover-on.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940 .soc-ico a:after {\n  border: 0px solid transparent;\n}\n#page .dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940 .soc-ico a:not(:hover) .soc-font-icon {\n  color: #ffffff;\n  background: none;\n}\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940 .soc-ico a .soc-font-icon {\n  font-size: 16px;\n}\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940 .filter-bg-decoration .filter-categories a.act {\n  color: #fff;\n}\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940:not(.resize-by-browser-width) .dt-css-grid {\n  grid-row-gap: 10px;\n  grid-column-gap: 10px;\n  grid-template-columns: repeat(auto-fill,minmax(,1fr));\n}\n.cssgridlegacy.no-cssgrid .dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940:not(.resize-by-browser-width) .dt-css-grid,\n.no-cssgridlegacy.no-cssgrid .dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940:not(.resize-by-browser-width) .dt-css-grid {\n  display: flex;\n  flex-flow: row wrap;\n  margin: -5px;\n}\n.cssgridlegacy.no-cssgrid .dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940:not(.resize-by-browser-width) .dt-css-grid .wf-cell,\n.no-cssgridlegacy.no-cssgrid .dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940:not(.resize-by-browser-width) .dt-css-grid .wf-cell {\n  flex: 1 0 ;\n  max-width: 100%;\n  padding: 5px;\n  box-sizing: border-box;\n}\n.dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940.resize-by-browser-width .dt-css-grid {\n  grid-template-columns: repeat(4,1fr);\n  grid-template-rows: auto;\n  grid-column-gap: 10px;\n  grid-row-gap: 10px;\n}\n.cssgridlegacy.no-cssgrid .dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940.resize-by-browser-width .dt-css-grid,\n.no-cssgridlegacy.no-cssgrid .dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940.resize-by-browser-width .dt-css-grid {\n  margin: -5px;\n}\n.cssgridlegacy.no-cssgrid .dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940.resize-by-browser-width .dt-css-grid .wf-cell,\n.no-cssgridlegacy.no-cssgrid .dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940.resize-by-browser-width .dt-css-grid .wf-cell {\n  width: 25%;\n  padding: 5px;\n}\n@media screen and (max-width: 1199px) {\n  .dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940.resize-by-browser-width .dt-css-grid {\n    grid-template-columns: repeat(4,1fr);\n  }\n  .cssgridlegacy.no-cssgrid .dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940.resize-by-browser-width .dt-css-grid .wf-cell,\n  .no-cssgridlegacy.no-cssgrid .dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940.resize-by-browser-width .dt-css-grid .wf-cell {\n    width: 25%;\n  }\n}\n@media screen and (max-width: 991px) {\n  .dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940.resize-by-browser-width .dt-css-grid {\n    grid-template-columns: repeat(3,1fr);\n  }\n  .cssgridlegacy.no-cssgrid .dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940.resize-by-browser-width .dt-css-grid .wf-cell,\n  .no-cssgridlegacy.no-cssgrid .dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940.resize-by-browser-width .dt-css-grid .wf-cell {\n    width: 33.333333333333%;\n  }\n}\n@media screen and (max-width: 767px) {\n  .dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940.resize-by-browser-width .dt-css-grid {\n    grid-template-columns: repeat(2,1fr);\n  }\n  .cssgridlegacy.no-cssgrid .dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940.resize-by-browser-width .dt-css-grid .wf-cell,\n  .no-cssgridlegacy.no-cssgrid .dt-team-shortcode.team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940.resize-by-browser-width .dt-css-grid .wf-cell {\n    width: 50%;\n  }\n}\n<\/style><div class=\"dt-team-masonry-shortcode dt-team-shortcode team-masonry-shortcode-id-975b34f6fdcbc9723469d108ecf8d940 loading-effect-none mode-grid jquery-filter content-align-center content-bg-on dt-css-grid-wrap dt-css-grid-wrap dt-icon-bg-on dt-icon-border-on dt-icon-hover-bg-on dt-icon-border-hover-on move-icons-under-position resize-by-browser-width  \" data-padding=\"5px\" data-cur-page=\"1\" data-post-limit=\"-1\" data-pagination-mode=\"none\" data-desktop-columns-num=\"4\" data-v-tablet-columns-num=\"3\" data-h-tablet-columns-num=\"4\" data-phone-columns-num=\"2\" data-width=\"0px\" data-columns=\"0\"><div class=\"dt-css-grid\" ><div class=\"visible wf-cell\" data-post-id=\"62438\" data-date=\"2020-02-01T11:36:39+07:00\" data-name=\"\u0e97\u0ec8\u0eb2\u0e99 \u0e99\u0eb2\u0e87 \u0ead\u0eb8\u0e97\u0ead\u0e99 \u0e84\u0eb3\u0e94\u0eb5\u0e9e\u0eb4\u0e9e\u0eb1\u0e81\"><div class=\"team-container visible post post-62438 dt_team type-dt_team status-publish has-post-thumbnail hentry dt_team_category-head-of-business-unit-1_la dt_team_category-1413 description-off\"><div class=\"team-media\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%99-%e0%ba%ad%e0%ba%b8%e0%ba%97%e0%ba%ad%e0%ba%99-%e0%ba%84%e0%ba%b3%e0%ba%94%e0%ba%b5%e0%ba%9e%e0%ba%b4%e0%ba%9e%e0%ba%b1%e0%ba%81\/\" class=\"rollover layzr-bg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20694%20694&#39;%2F%3E\" data-src=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2022\/02\/Outone-3.jpg\" data-srcset=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2022\/02\/Outone-3.jpg 694w\" loading=\"eager\" style=\"--ratio: 694 \/ 694\" sizes=\"(max-width: 694px) 100vw, 694px\" width=\"694\" height=\"694\"   alt=\"\" \/><\/a><\/div><div class=\"team-desc\"><div class=\"team-author\"><div class=\"team-author-name\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%99-%e0%ba%ad%e0%ba%b8%e0%ba%97%e0%ba%ad%e0%ba%99-%e0%ba%84%e0%ba%b3%e0%ba%94%e0%ba%b5%e0%ba%9e%e0%ba%b4%e0%ba%9e%e0%ba%b1%e0%ba%81\/\">\u0e97\u0ec8\u0eb2\u0e99 \u0e99\u0eb2\u0e87 \u0ead\u0eb8\u0e97\u0ead\u0e99 \u0e84\u0eb3\u0e94\u0eb5\u0e9e\u0eb4\u0e9e\u0eb1\u0e81<\/a><\/div><p>\u0e9c\u0eb9\u0ec9\u0ead\u0eb3\u0e99\u0ea7\u0e8d\u0e81\u0eb2\u0e99 \u0e9a\u0eaa \u0ec2\u0e8a\u0e81\u0ec4\u0e8a\u0e88\u0eb0\u0ec0\u0ea5\u0eb5\u0e99\u0e82\u0ebb\u0e99\u0eaa\u0ebb\u0ec8\u0e87 \u0e88\u0eb3\u0e81\u0eb1\u0e94\u0e9c\u0eb9\u0ec9\u0e94\u0ebd\u0ea7<\/p><\/div><div class=\"team-content\"><\/div>\n<a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%99-%e0%ba%ad%e0%ba%b8%e0%ba%97%e0%ba%ad%e0%ba%99-%e0%ba%84%e0%ba%b3%e0%ba%94%e0%ba%b5%e0%ba%9e%e0%ba%b4%e0%ba%9e%e0%ba%b1%e0%ba%81\/\" class=\"post-details details-type-link\" aria-label=\"Read more about \u0e97\u0ec8\u0eb2\u0e99 \u0e99\u0eb2\u0e87 \u0ead\u0eb8\u0e97\u0ead\u0e99 \u0e84\u0eb3\u0e94\u0eb5\u0e9e\u0eb4\u0e9e\u0eb1\u0e81\">\u0ec0\u0e9a\u0eb5\u0ec8\u0e87\u0ea5\u0eb2\u0e8d\u0ea5\u0eb0\u0ead\u0ebd,<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n<\/div><\/div><\/div><div class=\"visible wf-cell\" data-post-id=\"62628\" data-date=\"2020-03-10T11:19:44+07:00\" data-name=\"\u0e95\u0eb3\u0ec1\u0edc\u0ec8\u0e87\u0eab\u0ea7\u0ec8\u0eb2\u0e87\"><div class=\"team-container visible post post-62628 dt_team type-dt_team status-publish has-post-thumbnail hentry dt_team_category-head-of-business-unit-1_la dt_team_category-1413 description-off\"><div class=\"team-media\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%aa%e0%ba%ad%e0%ba%99\/\" class=\"rollover layzr-bg\"><img decoding=\"async\" class=\"preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20690%20690&#39;%2F%3E\" data-src=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2020\/04\/Vaccant-690x690.png\" data-srcset=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2020\/04\/Vaccant-690x690.png 690w\" loading=\"eager\" style=\"--ratio: 690 \/ 690\" sizes=\"(max-width: 690px) 100vw, 690px\" width=\"690\" height=\"690\"   alt=\"\" \/><\/a><\/div><div class=\"team-desc\"><div class=\"team-author\"><div class=\"team-author-name\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%aa%e0%ba%ad%e0%ba%99\/\">\u0e95\u0eb3\u0ec1\u0edc\u0ec8\u0e87\u0eab\u0ea7\u0ec8\u0eb2\u0e87<\/a><\/div><p>\u0e9c\u0eb8\u0ec9\u0e88\u0eb1\u0e94\u0e81\u0eb2\u0e99\u0eab\u0ea7\u0e8d\u0e97\u0eb1\u0e99\u0eaa\u0eb0\u0ec3\u0edd\u0ec2\u0e8a\u0e81\u0ec4\u0e8a<\/p><\/div><div class=\"team-content\"><\/div>\n<a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%aa%e0%ba%ad%e0%ba%99\/\" class=\"post-details details-type-link\" aria-label=\"Read more about \u0e95\u0eb3\u0ec1\u0edc\u0ec8\u0e87\u0eab\u0ea7\u0ec8\u0eb2\u0e87\">\u0ec0\u0e9a\u0eb5\u0ec8\u0e87\u0ea5\u0eb2\u0e8d\u0ea5\u0eb0\u0ead\u0ebd,<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n<\/div><\/div><\/div><div class=\"visible wf-cell\" data-post-id=\"62432\" data-date=\"2020-04-01T11:25:57+07:00\" data-name=\"\u0e97\u0ec8\u0eb2\u0e99 \u0eaa\u0ead\u0e99\u0e9b\u0eb0\u0ec0\u0eaa\u0eb5\u0e94 \u0e84\u0eb1\u0e99\u0e97\u0eb0\u0ea7\u0ebb\u0e87\"><div class=\"team-container visible post post-62432 dt_team type-dt_team status-publish has-post-thumbnail hentry dt_team_category-head-of-business-unit-1_la dt_team_category-1413 description-off\"><div class=\"team-media\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%aa%e0%ba%ad%e0%ba%99%e0%ba%9b%e0%ba%b0%e0%bb%80%e0%ba%aa%e0%ba%b5%e0%ba%94-%e0%ba%82%e0%ba%b1%e0%ba%99%e0%ba%97%e0%ba%b0%e0%ba%a7%e0%ba%bb%e0%ba%87\/\" class=\"rollover layzr-bg\"><img decoding=\"async\" class=\"preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20694%20694&#39;%2F%3E\" data-src=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2022\/02\/sonepasert-3.jpg\" data-srcset=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2022\/02\/sonepasert-3.jpg 694w\" loading=\"eager\" style=\"--ratio: 694 \/ 694\" sizes=\"(max-width: 694px) 100vw, 694px\" width=\"694\" height=\"694\"   alt=\"\" \/><\/a><\/div><div class=\"team-desc\"><div class=\"team-author\"><div class=\"team-author-name\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%aa%e0%ba%ad%e0%ba%99%e0%ba%9b%e0%ba%b0%e0%bb%80%e0%ba%aa%e0%ba%b5%e0%ba%94-%e0%ba%82%e0%ba%b1%e0%ba%99%e0%ba%97%e0%ba%b0%e0%ba%a7%e0%ba%bb%e0%ba%87\/\">\u0e97\u0ec8\u0eb2\u0e99 \u0eaa\u0ead\u0e99\u0e9b\u0eb0\u0ec0\u0eaa\u0eb5\u0e94 \u0e84\u0eb1\u0e99\u0e97\u0eb0\u0ea7\u0ebb\u0e87<\/a><\/div><p>\u0e9c\u0eb9\u0ec9\u0ead\u0eb3\u0e99\u0ea7\u0e8d\u0e81\u0eb2\u0e99 \u0e9a\u0eaa \u0ec2\u0e8a\u0e81\u0ec4\u0e8a\u0e9b\u0eb0\u0e81\u0eb1\u0e99\u0ec4\u0e9e \u0e88\u0eb3\u0e81\u0eb1\u0e94\u0e9c\u0eb9\u0ec9\u0e94\u0ebd\u0ea7<\/p><\/div><div class=\"team-content\"><\/div>\n<a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%aa%e0%ba%ad%e0%ba%99%e0%ba%9b%e0%ba%b0%e0%bb%80%e0%ba%aa%e0%ba%b5%e0%ba%94-%e0%ba%82%e0%ba%b1%e0%ba%99%e0%ba%97%e0%ba%b0%e0%ba%a7%e0%ba%bb%e0%ba%87\/\" class=\"post-details details-type-link\" aria-label=\"Read more about \u0e97\u0ec8\u0eb2\u0e99 \u0eaa\u0ead\u0e99\u0e9b\u0eb0\u0ec0\u0eaa\u0eb5\u0e94 \u0e84\u0eb1\u0e99\u0e97\u0eb0\u0ea7\u0ebb\u0e87\">\u0ec0\u0e9a\u0eb5\u0ec8\u0e87\u0ea5\u0eb2\u0e8d\u0ea5\u0eb0\u0ead\u0ebd,<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n<\/div><\/div><\/div><div class=\"visible wf-cell\" data-post-id=\"62518\" data-date=\"2020-05-01T17:03:26+07:00\" data-name=\"\u0e97\u0ec8\u0eb2\u0e99 \u0eaa\u0eb4\u0e99\u0e97\u0eb0\u0ea7\u0ebb\u0e87 \u0eaa\u0eb5\u0e8d\u0eb2\u0ea7\u0ebb\u0e87\"><div class=\"team-container visible post post-62518 dt_team type-dt_team status-publish has-post-thumbnail hentry dt_team_category-head-of-business-unit-1_la dt_team_category-1413 description-off\"><div class=\"team-media\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%aa%e0%ba%b4%e0%ba%99%e0%ba%97%e0%ba%b0%e0%ba%a7%e0%ba%bb%e0%ba%87-%e0%ba%aa%e0%ba%b5%e0%ba%8d%e0%ba%b2%e0%ba%a7%e0%ba%bb%e0%ba%87\/\" class=\"rollover layzr-bg\"><img decoding=\"async\" class=\"preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20694%20694&#39;%2F%3E\" data-src=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2022\/02\/Sin-4.jpg\" data-srcset=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2022\/02\/Sin-4.jpg 694w\" loading=\"eager\" style=\"--ratio: 694 \/ 694\" sizes=\"(max-width: 694px) 100vw, 694px\" width=\"694\" height=\"694\"   alt=\"\" \/><\/a><\/div><div class=\"team-desc\"><div class=\"team-author\"><div class=\"team-author-name\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%aa%e0%ba%b4%e0%ba%99%e0%ba%97%e0%ba%b0%e0%ba%a7%e0%ba%bb%e0%ba%87-%e0%ba%aa%e0%ba%b5%e0%ba%8d%e0%ba%b2%e0%ba%a7%e0%ba%bb%e0%ba%87\/\">\u0e97\u0ec8\u0eb2\u0e99 \u0eaa\u0eb4\u0e99\u0e97\u0eb0\u0ea7\u0ebb\u0e87 \u0eaa\u0eb5\u0e8d\u0eb2\u0ea7\u0ebb\u0e87<\/a><\/div><p>\u0e9c\u0eb8\u0ec9\u0ead\u0eb3\u0e99\u0ea7\u0e8d\u0e81\u0eb2\u0e99 \u0e9a\u0eaa \u0ec2\u0e8a\u0e81\u0ec4\u0e8a\u0ea1\u0eb2\u0e94 \u0ec1\u0ea5\u0eb0 \u0ec0\u0e9b\u0eb1\u0e99\u0eab\u0ebb\u0ea7\u0edc\u0ec9\u0eb2\u0e88\u0eb1\u0e94\u0e8a\u0eb7\u0ec9\u0e82\u0ead\u0e87\u0e81\u0eb8\u0ec8\u0ea1 \u0e9a\u0eaa \u0ec2\u0e8a\u0e81\u0ec4\u0e8a<\/p><\/div><div class=\"team-content\"><\/div>\n<a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%aa%e0%ba%b4%e0%ba%99%e0%ba%97%e0%ba%b0%e0%ba%a7%e0%ba%bb%e0%ba%87-%e0%ba%aa%e0%ba%b5%e0%ba%8d%e0%ba%b2%e0%ba%a7%e0%ba%bb%e0%ba%87\/\" class=\"post-details details-type-link\" aria-label=\"Read more about \u0e97\u0ec8\u0eb2\u0e99 \u0eaa\u0eb4\u0e99\u0e97\u0eb0\u0ea7\u0ebb\u0e87 \u0eaa\u0eb5\u0e8d\u0eb2\u0ea7\u0ebb\u0e87\">\u0ec0\u0e9a\u0eb5\u0ec8\u0e87\u0ea5\u0eb2\u0e8d\u0ea5\u0eb0\u0ead\u0ebd,<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n<\/div><\/div><\/div><div class=\"visible wf-cell\" data-post-id=\"62505\" data-date=\"2020-06-01T15:58:31+07:00\" data-name=\"\u0e97\u0ec8\u0eb2\u0e99 \u0ec2\u0ea5\u0ec0\u0ea5 \u0ec4\u0e8a\u0ead\u0eb8\u0e97\u0ead\u0e99\"><div class=\"team-container visible post post-62505 dt_team type-dt_team status-publish has-post-thumbnail hentry dt_team_category-head-of-business-unit-1_la dt_team_category-1413 description-off\"><div class=\"team-media\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%bb%82%e0%ba%a5%e0%bb%80%e0%ba%a5-%e0%bb%84%e0%ba%8a%e0%ba%ad%e0%ba%b8%e0%ba%97%e0%ba%ad%e0%ba%99\/\" class=\"rollover layzr-bg\"><img decoding=\"async\" class=\"preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20694%20694&#39;%2F%3E\" data-src=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2022\/02\/Loley-3.jpg\" data-srcset=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2022\/02\/Loley-3.jpg 694w\" loading=\"eager\" style=\"--ratio: 694 \/ 694\" sizes=\"(max-width: 694px) 100vw, 694px\" width=\"694\" height=\"694\"   alt=\"\" \/><\/a><\/div><div class=\"team-desc\"><div class=\"team-author\"><div class=\"team-author-name\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%bb%82%e0%ba%a5%e0%bb%80%e0%ba%a5-%e0%bb%84%e0%ba%8a%e0%ba%ad%e0%ba%b8%e0%ba%97%e0%ba%ad%e0%ba%99\/\">\u0e97\u0ec8\u0eb2\u0e99 \u0ec2\u0ea5\u0ec0\u0ea5 \u0ec4\u0e8a\u0ead\u0eb8\u0e97\u0ead\u0e99<\/a><\/div><p>\u0e9c\u0eb8\u0ec9\u0ead\u0eb3\u0e99\u0ea7\u0e8d\u0e81\u0eb2\u0e99 \u0e9a\u0eaa \u0ec2\u0e8a\u0e81\u0ec4\u0e8a\u0e88\u0eb0\u0ec0\u0ea5\u0eb5\u0e99\u0e81\u0ecd\u0ec8\u0eaa\u0ec9\u0eb2\u0e87 \u0e88\u0eb3\u0e81\u0eb1\u0e94\u0e9c\u0eb9\u0ec9\u0e94\u0ebd\u0ea7\r\n\r\n<\/p><\/div><div class=\"team-content\"><\/div>\n<a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%bb%82%e0%ba%a5%e0%bb%80%e0%ba%a5-%e0%bb%84%e0%ba%8a%e0%ba%ad%e0%ba%b8%e0%ba%97%e0%ba%ad%e0%ba%99\/\" class=\"post-details details-type-link\" aria-label=\"Read more about \u0e97\u0ec8\u0eb2\u0e99 \u0ec2\u0ea5\u0ec0\u0ea5 \u0ec4\u0e8a\u0ead\u0eb8\u0e97\u0ead\u0e99\">\u0ec0\u0e9a\u0eb5\u0ec8\u0e87\u0ea5\u0eb2\u0e8d\u0ea5\u0eb0\u0ead\u0ebd,<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n<\/div><\/div><\/div><div class=\"visible wf-cell\" data-post-id=\"62504\" data-date=\"2020-07-01T15:57:16+07:00\" data-name=\"\u0e97\u0ec8\u0eb2\u0e99 \u0e88\u0eb1\u0e81\u0e81\u0eb0\u0e9e\u0ebb\u0e87 \u0ea7\u0eb1\u0e87\u0e95\u0eb0\u0e9e\u0eb9\u0ea1\"><div class=\"team-container visible post post-62504 dt_team type-dt_team status-publish has-post-thumbnail hentry dt_team_category-head-of-business-unit-1_la dt_team_category-1413 description-off\"><div class=\"team-media\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%88%e0%ba%b1%e0%ba%81%e0%ba%81%e0%ba%b0%e0%ba%9e%e0%ba%bb%e0%ba%87-%e0%ba%a7%e0%ba%b1%e0%ba%87%e0%ba%95%e0%ba%b0%e0%ba%9e%e0%ba%b9%e0%ba%a1-2\/\" class=\"rollover layzr-bg\"><img decoding=\"async\" class=\"preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20694%20694&#39;%2F%3E\" data-src=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2022\/02\/jack-3.jpg\" data-srcset=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2022\/02\/jack-3.jpg 694w\" loading=\"eager\" style=\"--ratio: 694 \/ 694\" sizes=\"(max-width: 694px) 100vw, 694px\" width=\"694\" height=\"694\"   alt=\"\" \/><\/a><\/div><div class=\"team-desc\"><div class=\"team-author\"><div class=\"team-author-name\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%88%e0%ba%b1%e0%ba%81%e0%ba%81%e0%ba%b0%e0%ba%9e%e0%ba%bb%e0%ba%87-%e0%ba%a7%e0%ba%b1%e0%ba%87%e0%ba%95%e0%ba%b0%e0%ba%9e%e0%ba%b9%e0%ba%a1-2\/\">\u0e97\u0ec8\u0eb2\u0e99 \u0e88\u0eb1\u0e81\u0e81\u0eb0\u0e9e\u0ebb\u0e87 \u0ea7\u0eb1\u0e87\u0e95\u0eb0\u0e9e\u0eb9\u0ea1<\/a><\/div><p>\u0e9c\u0eb9\u0ec9\u0ead\u0eb3\u0e99\u0ea7\u0e8d\u0e81\u0eb2\u0e99 \u0e9a\u0eaa \u0ead\u0eb2\u0eab\u0eb2\u0e99 \u0ec1\u0ea5\u0eb0 \u0ec0\u0e84\u0eb7\u0ec8\u0ead\u0e87\u0e94\u0eb7\u0ec8\u0ea1 \u0ec2\u0e8a\u0e81\u0ec4\u0e8a \u0e88\u0eb3\u0e81\u0eb1\u0e94\u0e9c\u0eb9\u0ec9\u0e94\u0ebd\u0ea7\r\n\r\n\r\n<\/p><\/div><div class=\"team-content\"><\/div>\n<a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%88%e0%ba%b1%e0%ba%81%e0%ba%81%e0%ba%b0%e0%ba%9e%e0%ba%bb%e0%ba%87-%e0%ba%a7%e0%ba%b1%e0%ba%87%e0%ba%95%e0%ba%b0%e0%ba%9e%e0%ba%b9%e0%ba%a1-2\/\" class=\"post-details details-type-link\" aria-label=\"Read more about \u0e97\u0ec8\u0eb2\u0e99 \u0e88\u0eb1\u0e81\u0e81\u0eb0\u0e9e\u0ebb\u0e87 \u0ea7\u0eb1\u0e87\u0e95\u0eb0\u0e9e\u0eb9\u0ea1\">\u0ec0\u0e9a\u0eb5\u0ec8\u0e87\u0ea5\u0eb2\u0e8d\u0ea5\u0eb0\u0ead\u0ebd,<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n<\/div><\/div><\/div><div class=\"visible wf-cell\" data-post-id=\"62445\" data-date=\"2022-02-01T11:49:57+07:00\" data-name=\"\u0e97\u0ec8\u0eb2\u0e99 \u0e99\u0eb2\u0e87 \u0e99\u0eb1\u0e94\u0e96\u0eb2\u0ea7\u0eb0\u0ea5\u0eb5 \u0e95\u0eb0\u0ea7\u0eb4\u0ec4\u0e8a\"><div class=\"team-container visible post post-62445 dt_team type-dt_team status-publish has-post-thumbnail hentry dt_team_category-head-of-business-unit-1_la dt_team_category-1413 description-off\"><div class=\"team-media\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%99%e0%ba%b2%e0%ba%87-%e0%ba%99%e0%ba%b1%e0%ba%94%e0%ba%96%e0%ba%b2%e0%ba%a7%e0%ba%b0%e0%ba%a5%e0%ba%b5-%e0%ba%95%e0%ba%b0%e0%ba%a7%e0%ba%b4%e0%bb%84\/\" class=\"rollover layzr-bg\"><img decoding=\"async\" class=\"preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20694%20694&#39;%2F%3E\" data-src=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2022\/02\/vi-3.jpg\" data-srcset=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2022\/02\/vi-3.jpg 694w\" loading=\"eager\" style=\"--ratio: 694 \/ 694\" sizes=\"(max-width: 694px) 100vw, 694px\" width=\"694\" height=\"694\"   alt=\"\" \/><\/a><\/div><div class=\"team-desc\"><div class=\"team-author\"><div class=\"team-author-name\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%99%e0%ba%b2%e0%ba%87-%e0%ba%99%e0%ba%b1%e0%ba%94%e0%ba%96%e0%ba%b2%e0%ba%a7%e0%ba%b0%e0%ba%a5%e0%ba%b5-%e0%ba%95%e0%ba%b0%e0%ba%a7%e0%ba%b4%e0%bb%84\/\">\u0e97\u0ec8\u0eb2\u0e99 \u0e99\u0eb2\u0e87 \u0e99\u0eb1\u0e94\u0e96\u0eb2\u0ea7\u0eb0\u0ea5\u0eb5 \u0e95\u0eb0\u0ea7\u0eb4\u0ec4\u0e8a<\/a><\/div><p>\u0e9c\u0eb9\u0ec9\u0ead\u0eb3\u0e99\u0ea7\u0e8d\u0e81\u0eb2\u0e99 \u0e9a\u0eaa \u0ec2\u0e8a\u0e81\u0ec4\u0e8a \u0e9b\u0eb0\u0e81\u0eb1\u0e99\u0ec4\u0e9e\u0e8a\u0eb5\u0ea7\u0eb4\u0e94 \u0e88\u0eb3\u0e81\u0eb1\u0e94\u0e9c\u0eb9\u0ec9\u0e94\u0ebd\u0ea7\r\n\r\n<\/p><\/div><div class=\"team-content\"><\/div>\n<a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%99%e0%ba%b2%e0%ba%87-%e0%ba%99%e0%ba%b1%e0%ba%94%e0%ba%96%e0%ba%b2%e0%ba%a7%e0%ba%b0%e0%ba%a5%e0%ba%b5-%e0%ba%95%e0%ba%b0%e0%ba%a7%e0%ba%b4%e0%bb%84\/\" class=\"post-details details-type-link\" aria-label=\"Read more about \u0e97\u0ec8\u0eb2\u0e99 \u0e99\u0eb2\u0e87 \u0e99\u0eb1\u0e94\u0e96\u0eb2\u0ea7\u0eb0\u0ea5\u0eb5 \u0e95\u0eb0\u0ea7\u0eb4\u0ec4\u0e8a\">\u0ec0\u0e9a\u0eb5\u0ec8\u0e87\u0ea5\u0eb2\u0e8d\u0ea5\u0eb0\u0ead\u0ebd,<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n<\/div><\/div><\/div><div class=\"visible wf-cell\" data-post-id=\"62455\" data-date=\"2022-02-01T12:00:00+07:00\" data-name=\"\u0e97\u0ec8\u0eb2\u0e99 \u0eaa\u0ead\u0e99 \u0e9e\u0ebb\u0e87\u0ec0\u0e9e\u0eb1\u0e94\"><div class=\"team-container visible post post-62455 dt_team type-dt_team status-publish has-post-thumbnail hentry dt_team_category-head-of-business-unit-1_la dt_team_category-1413 description-off\"><div class=\"team-media\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%aa%e0%ba%ad%e0%ba%99-%e0%ba%9e%e0%ba%bb%e0%ba%87%e0%bb%80%e0%ba%9e%e0%ba%b1%e0%ba%94\/\" class=\"rollover layzr-bg\"><img decoding=\"async\" class=\"preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20694%20694&#39;%2F%3E\" data-src=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2022\/02\/phongphet-3.jpg\" data-srcset=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2022\/02\/phongphet-3.jpg 694w\" loading=\"eager\" style=\"--ratio: 694 \/ 694\" sizes=\"(max-width: 694px) 100vw, 694px\" width=\"694\" height=\"694\"   alt=\"\" \/><\/a><\/div><div class=\"team-desc\"><div class=\"team-author\"><div class=\"team-author-name\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%aa%e0%ba%ad%e0%ba%99-%e0%ba%9e%e0%ba%bb%e0%ba%87%e0%bb%80%e0%ba%9e%e0%ba%b1%e0%ba%94\/\">\u0e97\u0ec8\u0eb2\u0e99 \u0eaa\u0ead\u0e99 \u0e9e\u0ebb\u0e87\u0ec0\u0e9e\u0eb1\u0e94<\/a><\/div><p>\u0e9c\u0eb9\u0ec9\u0ead\u0eb3\u0e99\u0ea7\u0e8d\u0e81\u0eb2\u0e99 \u0e9a\u0eaa \u0ec2\u0e8a\u0e81\u0ec4\u0e8a\u0e88\u0eb0\u0ec0\u0ea5\u0eb5\u0e99\u0e81\u0eb2\u0e99\u0e84\u0ec9\u0eb2 \u0e88\u0eb3\u0e81\u0eb1\u0e94\u0e9c\u0eb9\u0ec9\u0e94\u0ebd\u0ea7\r\n\r\n\r\n<\/p><\/div><div class=\"team-content\"><\/div>\n<a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%aa%e0%ba%ad%e0%ba%99-%e0%ba%9e%e0%ba%bb%e0%ba%87%e0%bb%80%e0%ba%9e%e0%ba%b1%e0%ba%94\/\" class=\"post-details details-type-link\" aria-label=\"Read more about \u0e97\u0ec8\u0eb2\u0e99 \u0eaa\u0ead\u0e99 \u0e9e\u0ebb\u0e87\u0ec0\u0e9e\u0eb1\u0e94\">\u0ec0\u0e9a\u0eb5\u0ec8\u0e87\u0ea5\u0eb2\u0e8d\u0ea5\u0eb0\u0ead\u0ebd,<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n<\/div><\/div><\/div><div class=\"visible wf-cell\" data-post-id=\"62509\" data-date=\"2022-02-01T16:13:52+07:00\" data-name=\"\u0e97\u0ec8\u0eb2\u0e99 \u0e9b\u0eb2\u0e81\u0eb5\u0ec4\u0e99 \u0e9a\u0eb8\u0e99\u0e9a\u0eb1\u0e99\u0e88\u0ebb\u0e9a\"><div class=\"team-container visible post post-62509 dt_team type-dt_team status-publish has-post-thumbnail hentry dt_team_category-head-of-business-unit-1_la dt_team_category-1413 description-off\"><div class=\"team-media\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%9b%e0%ba%b2%e0%ba%81%e0%ba%b5%e0%bb%84%e0%ba%99-%e0%ba%9a%e0%ba%b8%e0%ba%99%e0%ba%9a%e0%ba%b1%e0%ba%99%e0%ba%88%e0%ba%bb%e0%ba%9a\/\" class=\"rollover layzr-bg\"><img decoding=\"async\" class=\"preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20694%20694&#39;%2F%3E\" data-src=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2022\/02\/Kinay-3.jpg\" data-srcset=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2022\/02\/Kinay-3.jpg 694w\" loading=\"eager\" style=\"--ratio: 694 \/ 694\" sizes=\"(max-width: 694px) 100vw, 694px\" width=\"694\" height=\"694\"   alt=\"\" \/><\/a><\/div><div class=\"team-desc\"><div class=\"team-author\"><div class=\"team-author-name\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%9b%e0%ba%b2%e0%ba%81%e0%ba%b5%e0%bb%84%e0%ba%99-%e0%ba%9a%e0%ba%b8%e0%ba%99%e0%ba%9a%e0%ba%b1%e0%ba%99%e0%ba%88%e0%ba%bb%e0%ba%9a\/\">\u0e97\u0ec8\u0eb2\u0e99 \u0e9b\u0eb2\u0e81\u0eb5\u0ec4\u0e99 \u0e9a\u0eb8\u0e99\u0e9a\u0eb1\u0e99\u0e88\u0ebb\u0e9a<\/a><\/div><p>\u0e9c\u0eb9\u0ec9\u0ead\u0eb3\u0e99\u0ea7\u0e8d\u0e81\u0eb2\u0e99 \u0e9a\u0eaa \u0ec2\u0e8a\u0e81\u0ec4\u0e8a\u0e88\u0eb0\u0ec0\u0ea5\u0eb5\u0e99\u0e84\u0ead\u0e99\u0e81\u0eb5\u0e94\u0e88\u0eb3\u0e81\u0eb1\u0e94\u0e9c\u0eb9\u0ec9\u0e94\u0ebd\u0ea7\r\n\r\n<\/p><\/div><div class=\"team-content\"><\/div>\n<a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%9b%e0%ba%b2%e0%ba%81%e0%ba%b5%e0%bb%84%e0%ba%99-%e0%ba%9a%e0%ba%b8%e0%ba%99%e0%ba%9a%e0%ba%b1%e0%ba%99%e0%ba%88%e0%ba%bb%e0%ba%9a\/\" class=\"post-details details-type-link\" aria-label=\"Read more about \u0e97\u0ec8\u0eb2\u0e99 \u0e9b\u0eb2\u0e81\u0eb5\u0ec4\u0e99 \u0e9a\u0eb8\u0e99\u0e9a\u0eb1\u0e99\u0e88\u0ebb\u0e9a\">\u0ec0\u0e9a\u0eb5\u0ec8\u0e87\u0ea5\u0eb2\u0e8d\u0ea5\u0eb0\u0ead\u0ebd,<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n<\/div><\/div><\/div><div class=\"visible wf-cell\" data-post-id=\"62641\" data-date=\"2022-02-10T13:35:27+07:00\" data-name=\"\u0e97\u0ec8\u0eb2\u0e99 \u0ea7\u0eb4\u0ec4\u0e99 \u0ec1\u0e81\u0ec9\u0ea7\u0e84\u0eb3\u0e9e\u0eb1\u0e99\"><div class=\"team-container visible post post-62641 dt_team type-dt_team status-publish has-post-thumbnail hentry dt_team_category-head-of-business-unit-1_la dt_team_category-1413 description-off\"><div class=\"team-media\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%a7%e0%ba%b4%e0%bb%84%e0%ba%99-%e0%bb%81%e0%ba%81%e0%bb%89%e0%ba%a7%e0%ba%84%e0%ba%b3%e0%ba%9e%e0%ba%b1%e0%ba%99\/\" class=\"rollover layzr-bg\"><img decoding=\"async\" class=\"preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20694%20694&#39;%2F%3E\" data-src=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2022\/02\/Vinay-3.jpg\" data-srcset=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2022\/02\/Vinay-3.jpg 694w\" loading=\"eager\" style=\"--ratio: 694 \/ 694\" sizes=\"(max-width: 694px) 100vw, 694px\" width=\"694\" height=\"694\"   alt=\"\" \/><\/a><\/div><div class=\"team-desc\"><div class=\"team-author\"><div class=\"team-author-name\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%a7%e0%ba%b4%e0%bb%84%e0%ba%99-%e0%bb%81%e0%ba%81%e0%bb%89%e0%ba%a7%e0%ba%84%e0%ba%b3%e0%ba%9e%e0%ba%b1%e0%ba%99\/\">\u0e97\u0ec8\u0eb2\u0e99 \u0ea7\u0eb4\u0ec4\u0e99 \u0ec1\u0e81\u0ec9\u0ea7\u0e84\u0eb3\u0e9e\u0eb1\u0e99<\/a><\/div><p>\u0e9c\u0eb9\u0ec9\u0ead\u0ecd\u0eb2\u0e99\u0ea7\u0e8d\u0e81\u0eb2\u0e99 \u0e9a\u0eaa \u0e94\u0eb5\u0e94\u0eb5\u0e9a\u0ecd\u0ea5\u0eb4\u0e81\u0eb2\u0e99\u0e88\u0eb1\u0e94\u0eab\u0eb2\u0e87\u0eb2\u0e99 \u0e88\u0eb3\u0e81\u0eb1\u0e94\u0e9c\u0eb9\u0ec9\u0e94\u0ebd\u0ea7<\/p><\/div><div class=\"team-content\"><\/div>\n<a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/%e0%ba%97%e0%bb%88%e0%ba%b2%e0%ba%99-%e0%ba%a7%e0%ba%b4%e0%bb%84%e0%ba%99-%e0%bb%81%e0%ba%81%e0%bb%89%e0%ba%a7%e0%ba%84%e0%ba%b3%e0%ba%9e%e0%ba%b1%e0%ba%99\/\" class=\"post-details details-type-link\" aria-label=\"Read more about \u0e97\u0ec8\u0eb2\u0e99 \u0ea7\u0eb4\u0ec4\u0e99 \u0ec1\u0e81\u0ec9\u0ea7\u0e84\u0eb3\u0e9e\u0eb1\u0e99\">\u0ec0\u0e9a\u0eb5\u0ec8\u0e87\u0ea5\u0eb2\u0e8d\u0ea5\u0eb0\u0ead\u0ebd,<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n<\/div><\/div><\/div><div class=\"visible wf-cell\" data-post-id=\"62659\" data-date=\"2022-02-10T15:01:13+07:00\" data-name=\"\u0e97\u0ec8\u0eb2\u0e99 \u0ea7\u0eb4\u0ea5\u0eb0\u0eaa\u0eb1\u0e81 \u0ea7\u0eb1\u0e99\u0e99\u0eb0\u0ec0\u0e94\u0e94\"><div class=\"team-container visible post post-62659 dt_team type-dt_team status-publish has-post-thumbnail hentry dt_team_category-head-of-business-unit-1_la dt_team_category-1413 description-off\"><div class=\"team-media\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/mr-somchit\/\" class=\"rollover layzr-bg\"><img decoding=\"async\" class=\"preload-me iso-lazy-load aspect\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%20694%20694&#39;%2F%3E\" data-src=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2022\/06\/Pedd-2.jpg\" data-srcset=\"https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2022\/06\/Pedd-2.jpg 694w\" loading=\"eager\" style=\"--ratio: 694 \/ 694\" sizes=\"(max-width: 694px) 100vw, 694px\" width=\"694\" height=\"694\"   alt=\"\" \/><\/a><\/div><div class=\"team-desc\"><div class=\"team-author\"><div class=\"team-author-name\"><a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/mr-somchit\/\">\u0e97\u0ec8\u0eb2\u0e99 \u0ea7\u0eb4\u0ea5\u0eb0\u0eaa\u0eb1\u0e81 \u0ea7\u0eb1\u0e99\u0e99\u0eb0\u0ec0\u0e94\u0e94<\/a><\/div><p>\u0e9c\u0eb8\u0ec9\u0ead\u0eb3\u0e99\u0ea7\u0e8d\u0e81\u0eb2\u0e99\u0ec2\u0e8a\u0e81\u0ec4\u0e8a\u0ead\u0eb5\u0e84\u0ead\u0ea1\u0ec0\u0ea1\u0eb5\u0eaa\u0e88\u0eb3\u0e81\u0eb1\u0e94\u0e9c\u0eb9\u0ec9\u0e94\u0ebd\u0ea7<\/p><\/div><div class=\"team-content\"><\/div>\n<a href=\"https:\/\/sokxaygroup.com\/sxgroup\/dt_team\/mr-somchit\/\" class=\"post-details details-type-link\" aria-label=\"Read more about \u0e97\u0ec8\u0eb2\u0e99 \u0ea7\u0eb4\u0ea5\u0eb0\u0eaa\u0eb1\u0e81 \u0ea7\u0eb1\u0e99\u0e99\u0eb0\u0ec0\u0e94\u0e94\">\u0ec0\u0e9a\u0eb5\u0ec8\u0e87\u0ea5\u0eb2\u0e8d\u0ea5\u0eb0\u0ead\u0ebd,<i class=\"dt-icon-the7-arrow-03\" aria-hidden=\"true\"><\/i><\/a>\n<\/div><\/div><\/div><\/div><!-- iso-container|iso-grid --><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1560847925785{padding-top: 60px !important;padding-bottom: 10px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1643692728710{margin-top: 50px !important;}&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221;][vc_column css=&#8221;.vc_custom_1560847982746{margin-bottom: -10px !important;}&#8221;]<div class=\"hr-thin style-line\" style=\"width: 100%;border-top-width: 1px;\"><\/div>[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1560848024112{padding-top: 60px !important;padding-bottom: 60px !important;}&#8221;][vc_column][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;vc_default&#8221; bg_type=&#8221;image&#8221; parallax_style=&#8221;vcpb-default&#8221; bg_image_new=&#8221;id^60302|url^https:\/\/sokxaygroup.com\/sxgroup\/wp-content\/uploads\/2019\/11\/bg-dev-studio-05.jpg|caption^null|alt^null|title^bg-dev-studio-05|description^null&#8221; bg_image_repeat=&#8221;no-repeat&#8221; bg_override=&#8221;full&#8221; css=&#8221;.vc_custom_1643693252938{margin-top: 50px !important;}&#8221;][vc_column][vc_row_inner][vc_column_inner css=&#8221;.vc_custom_1643693051470{margin-top: 50px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1560847925785{padding-top: 60px !important;padding-bottom: 10px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1643692728710{margin-top: 50px !important;}&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221;][vc_column css=&#8221;.vc_custom_1560847982746{margin-bottom: -10px !important;}&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1560848024112{padding-top: 60px !important;padding-bottom: 60px !important;}&#8221;][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":535,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-62464","page","type-page","status-publish","hentry","description-off"],"_links":{"self":[{"href":"https:\/\/sokxaygroup.com\/sxgroup\/wp-json\/wp\/v2\/pages\/62464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sokxaygroup.com\/sxgroup\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sokxaygroup.com\/sxgroup\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sokxaygroup.com\/sxgroup\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sokxaygroup.com\/sxgroup\/wp-json\/wp\/v2\/comments?post=62464"}],"version-history":[{"count":3,"href":"https:\/\/sokxaygroup.com\/sxgroup\/wp-json\/wp\/v2\/pages\/62464\/revisions"}],"predecessor-version":[{"id":62467,"href":"https:\/\/sokxaygroup.com\/sxgroup\/wp-json\/wp\/v2\/pages\/62464\/revisions\/62467"}],"wp:attachment":[{"href":"https:\/\/sokxaygroup.com\/sxgroup\/wp-json\/wp\/v2\/media?parent=62464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}